{"id":2628,"date":"2019-06-18T00:32:49","date_gmt":"2019-06-18T06:32:49","guid":{"rendered":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?p=2351"},"modified":"2022-10-14T11:34:52","modified_gmt":"2022-10-14T17:34:52","slug":"personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero","status":"publish","type":"post","link":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/","title":{"rendered":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1024x768.jpg\" alt=\"\" class=\"wp-image-2352\" width=\"768\" height=\"576\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS) a trav\u00e9s de la Gerencia de Protecci\u00f3n al Usuario Financiero (GPUF) brind\u00f3 al personal del Instituto Nacional de Jubilaciones y Pensiones de los Empleados y Funcionarios del Poder Ejecutivo (INJUPEMP), una conferencia sobre las Normas para el Fortalecimiento de la Transparencia, la Cultura Financiera y Atenci\u00f3n al Usuario Financiero en las Instituciones Supervisadas (Circulares CNBS 140\/2012 y 141\/2012), a cargo del Abg. Oscar Vel\u00e1squez y el Abg. Mario Ir\u00edas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los asistentes pudieron realizar consultas pertinentes a deberes y derechos de los usuarios, sobre el Sistema de Atenci\u00f3n a Reclamos, contratos, entre otros temas descritos en dichas circulares .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los asistentes reflexionaron sobre la importancia de que la CNBS fortaleciera sus conocimientos en tem\u00e1ticas de gran ayuda para todos los usuarios del sistema financiero <\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1-1024x768.jpg\" alt=\"\" data-id=\"2353\" data-link=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?attachment_id=2353\" class=\"wp-image-2353\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0024-1024x768.jpg\" alt=\"\" data-id=\"2355\" data-link=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?attachment_id=2355\" class=\"wp-image-2355\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS) a trav\u00e9s de la Gerencia de Protecci\u00f3n al Usuario Financiero (GPUF) brind\u00f3 al personal del Instituto Nacional de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[32,3],"tags":[],"class_list":["post-2628","post","type-post","status-publish","format-standard","hentry","category-ef","category-novedades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS) a trav\u00e9s de la Gerencia de Protecci\u00f3n al Usuario Financiero (GPUF) brind\u00f3 al personal del Instituto Nacional de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/\" \/>\n<meta property=\"og:site_name\" content=\"CNBS - GEIFG - Educaci\u00f3n Financiera\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-18T06:32:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-14T17:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"tlopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tlopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/\"},\"author\":{\"name\":\"tlopez\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/person\\\/6e2e33f00a004ebea7513144a8a4d423\"},\"headline\":\"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero\",\"datePublished\":\"2019-06-18T06:32:49+00:00\",\"dateModified\":\"2022-10-14T17:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/\"},\"wordCount\":151,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/IMG-20190613-WA0020-1024x768.jpg\",\"articleSection\":[\"Educaci\u00f3n Financiera\",\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/\",\"name\":\"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/IMG-20190613-WA0020-1024x768.jpg\",\"datePublished\":\"2019-06-18T06:32:49+00:00\",\"dateModified\":\"2022-10-14T17:34:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Foto-3-6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Foto-3-6.jpg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2019\\\/06\\\/18\\\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#website\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\",\"name\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\",\"name\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-CNBS-SOLO.png\",\"contentUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-CNBS-SOLO.png\",\"width\":2250,\"height\":2250,\"caption\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/person\\\/6e2e33f00a004ebea7513144a8a4d423\",\"name\":\"tlopez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g\",\"caption\":\"tlopez\"},\"sameAs\":[\"https:\\\/\\\/cnbs.gob.hn\\\/atencion-usuario-financiero\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/","og_locale":"es_ES","og_type":"article","og_title":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera","og_description":"La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS) a trav\u00e9s de la Gerencia de Protecci\u00f3n al Usuario Financiero (GPUF) brind\u00f3 al personal del Instituto Nacional de [\u2026]","og_url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/","og_site_name":"CNBS - GEIFG - Educaci\u00f3n Financiera","article_published_time":"2019-06-18T06:32:49+00:00","article_modified_time":"2022-10-14T17:34:52+00:00","og_image":[{"url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1024x768.jpg","type":"","width":"","height":""}],"author":"tlopez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"tlopez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#article","isPartOf":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/"},"author":{"name":"tlopez","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/person\/6e2e33f00a004ebea7513144a8a4d423"},"headline":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero","datePublished":"2019-06-18T06:32:49+00:00","dateModified":"2022-10-14T17:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/"},"wordCount":151,"publisher":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1024x768.jpg","articleSection":["Educaci\u00f3n Financiera","Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/","name":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero - CNBS - GEIFG - Educaci\u00f3n Financiera","isPartOf":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#primaryimage"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/06\/IMG-20190613-WA0020-1024x768.jpg","datePublished":"2019-06-18T06:32:49+00:00","dateModified":"2022-10-14T17:34:52+00:00","breadcrumb":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#primaryimage","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/01\/Foto-3-6.jpg","contentUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2019\/01\/Foto-3-6.jpg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2019\/06\/18\/personal-de-injupemp-recibe-conferencia-sobre-normas-de-transparencia-y-atencion-al-usuario-financiero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/"},{"@type":"ListItem","position":2,"name":"Personal de INJUPEMP recibe conferencia sobre Normas de Transparencia y Atenci\u00f3n al Usuario Financiero"}]},{"@type":"WebSite","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#website","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/","name":"CNBS - GEIFG - Educaci\u00f3n Financiera","description":"","publisher":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization","name":"CNBS - GEIFG - Educaci\u00f3n Financiera","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/logo\/image\/","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2020\/11\/Logo-CNBS-SOLO.png","contentUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2020\/11\/Logo-CNBS-SOLO.png","width":2250,"height":2250,"caption":"CNBS - GEIFG - Educaci\u00f3n Financiera"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/person\/6e2e33f00a004ebea7513144a8a4d423","name":"tlopez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc58880482c6ee59b25a6174fc7529a534a01c9a07533e96da00dd396ec184d5?s=96&d=mm&r=g","caption":"tlopez"},"sameAs":["https:\/\/cnbs.gob.hn\/atencion-usuario-financiero"]}]}},"_links":{"self":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/2628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/comments?post=2628"}],"version-history":[{"count":1,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/2628\/revisions"}],"predecessor-version":[{"id":2646,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/2628\/revisions\/2646"}],"wp:attachment":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/media?parent=2628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/categories?post=2628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/tags?post=2628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}