{"id":6676,"date":"2024-06-28T16:37:51","date_gmt":"2024-06-28T22:37:51","guid":{"rendered":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?p=6676"},"modified":"2024-07-02T16:39:13","modified_gmt":"2024-07-02T22:39:13","slug":"la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah","status":"publish","type":"post","link":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/","title":{"rendered":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH)"},"content":{"rendered":"<p>Redacci\u00f3n:\u00a0Luis L\u00f3pez.\u200b<\/p>\n<p>La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS), en el cumplimiento de su deber institucional, el pasado 18 y 24 de junio de 2024, brind\u00f3 de manera presencial y virtual, las charlas \u201cEducaci\u00f3n Financiera\u00bb y \u201cCentral de Informaci\u00f3n Crediticia\u201d a j\u00f3venes estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) de Tegucigalpa, con una asistencia de m\u00e1s de 200 participantes.<\/p>\n<p>Durante el desarrollo de los temas, los participantes fueron capaces de aprender a diferenciar qu\u00e9 es un producto financiero, la importancia de conocer sus deberes y derechos, que conlleva tomar decisiones debidamente informadas previo a la adquisici\u00f3n de los mismos y c\u00f3mo pueden ayudarle a alcanzar la libertad financiera. Adem\u00e1s, los participantes tuvieron la oportunidad de conocer qu\u00e9 es el ahorro y la importancia de realizar un control financiero; tambi\u00e9n, tuvieron la oportunidad de conocer que es la Central de Informaci\u00f3n Crediticia (CIC), su funci\u00f3n, importancia y como pueden acceder a su historial crediticio.<\/p>\n<p>Se agradecieron las ponencias impartidas por los Licenciados Juan Molina y Luis L\u00f3pez, Oficiales de Disciplina de Mercado y Transparencia, pertenecientes a la Gerencia de Educaci\u00f3n e Inclusi\u00f3n Financiera y G\u00e9nero.\u200b<\/p>\n<p><a href=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-6677\" src=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-1024x769.jpg 1024w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-300x225.jpg 300w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-768x577.jpg 768w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-1536x1153.jpg 1536w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-2048x1538.jpg 2048w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-194x146.jpg 194w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-50x38.jpg 50w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-100x75.jpg 100w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-960x720.jpg 960w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-750x563.jpg 750w, https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024-1140x856.jpg 1140w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n:\u00a0Luis L\u00f3pez.\u200b La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS), en el cumplimiento de su deber institucional, el pasado 18 y 24 de junio de 2024,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":7,"featured_media":6677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,32],"tags":[],"class_list":["post-6676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capacitaciones","category-ef"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera\" \/>\n<meta property=\"og:description\" content=\"Redacci\u00f3n:\u00a0Luis L\u00f3pez.\u200b La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS), en el cumplimiento de su deber institucional, el pasado 18 y 24 de junio de 2024, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/\" \/>\n<meta property=\"og:site_name\" content=\"CNBS - GEIFG - Educaci\u00f3n Financiera\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T22:37:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T22:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2312\" \/>\n\t<meta property=\"og:image:height\" content=\"1736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aar\u00f3n A. Mej\u00eda Godoy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aar\u00f3n A. Mej\u00eda Godoy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/\"},\"author\":{\"name\":\"Aar\u00f3n A. Mej\u00eda Godoy\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/person\\\/75e533192ab17d048de05523f994563f\"},\"headline\":\"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH)\",\"datePublished\":\"2024-06-28T22:37:51+00:00\",\"dateModified\":\"2024-07-02T22:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EDUCACION-UNAH-CIC-2024.jpg\",\"articleSection\":[\"Capacitaciones\",\"Educaci\u00f3n Financiera\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/\",\"name\":\"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EDUCACION-UNAH-CIC-2024.jpg\",\"datePublished\":\"2024-06-28T22:37:51+00:00\",\"dateModified\":\"2024-07-02T22:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EDUCACION-UNAH-CIC-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EDUCACION-UNAH-CIC-2024.jpg\",\"width\":2312,\"height\":1736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/2024\\\/06\\\/28\\\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#website\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\",\"name\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#organization\",\"name\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-CNBS-SOLO.png\",\"contentUrl\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-CNBS-SOLO.png\",\"width\":2250,\"height\":2250,\"caption\":\"CNBS - GEIFG - Educaci\u00f3n Financiera\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cnbs.gob.hn\\\/educacionfinanciera\\\/#\\\/schema\\\/person\\\/75e533192ab17d048de05523f994563f\",\"name\":\"Aar\u00f3n A. Mej\u00eda Godoy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g\",\"caption\":\"Aar\u00f3n A. Mej\u00eda Godoy\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/","og_locale":"es_ES","og_type":"article","og_title":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera","og_description":"Redacci\u00f3n:\u00a0Luis L\u00f3pez.\u200b La Comisi\u00f3n Nacional de Bancos y Seguros (CNBS), en el cumplimiento de su deber institucional, el pasado 18 y 24 de junio de 2024, [\u2026]","og_url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/","og_site_name":"CNBS - GEIFG - Educaci\u00f3n Financiera","article_published_time":"2024-06-28T22:37:51+00:00","article_modified_time":"2024-07-02T22:39:13+00:00","og_image":[{"width":2312,"height":1736,"url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg","type":"image\/jpeg"}],"author":"Aar\u00f3n A. Mej\u00eda Godoy","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aar\u00f3n A. Mej\u00eda Godoy","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#article","isPartOf":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/"},"author":{"name":"Aar\u00f3n A. Mej\u00eda Godoy","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/person\/75e533192ab17d048de05523f994563f"},"headline":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH)","datePublished":"2024-06-28T22:37:51+00:00","dateModified":"2024-07-02T22:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/"},"wordCount":222,"publisher":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg","articleSection":["Capacitaciones","Educaci\u00f3n Financiera"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/","name":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH) - CNBS - GEIFG - Educaci\u00f3n Financiera","isPartOf":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#primaryimage"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg","datePublished":"2024-06-28T22:37:51+00:00","dateModified":"2024-07-02T22:39:13+00:00","breadcrumb":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#primaryimage","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg","contentUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2024\/07\/EDUCACION-UNAH-CIC-2024.jpg","width":2312,"height":1736},{"@type":"BreadcrumbList","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/2024\/06\/28\/la-cnbs-capacito-en-temas-de-educacion-financiera-a-estudiantes-de-la-universidad-nacional-autonoma-de-honduras-unah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/"},{"@type":"ListItem","position":2,"name":"La CNBS capacit\u00f3 en temas de educaci\u00f3n financiera a estudiantes de la Universidad Nacional Aut\u00f3noma de Honduras (UNAH)"}]},{"@type":"WebSite","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#website","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/","name":"CNBS - GEIFG - Educaci\u00f3n Financiera","description":"","publisher":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#organization","name":"CNBS - GEIFG - Educaci\u00f3n Financiera","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/logo\/image\/","url":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2020\/11\/Logo-CNBS-SOLO.png","contentUrl":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-content\/uploads\/2020\/11\/Logo-CNBS-SOLO.png","width":2250,"height":2250,"caption":"CNBS - GEIFG - Educaci\u00f3n Financiera"},"image":{"@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/#\/schema\/person\/75e533192ab17d048de05523f994563f","name":"Aar\u00f3n A. Mej\u00eda Godoy","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5cb9148ccd44e9e7eb4698d056108d6432171016bc9c40c26f460d09f441c6e?s=96&d=mm&r=g","caption":"Aar\u00f3n A. Mej\u00eda Godoy"}}]}},"_links":{"self":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/6676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/comments?post=6676"}],"version-history":[{"count":1,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/6676\/revisions"}],"predecessor-version":[{"id":6678,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/posts\/6676\/revisions\/6678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/media\/6677"}],"wp:attachment":[{"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/media?parent=6676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/categories?post=6676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cnbs.gob.hn\/educacionfinanciera\/wp-json\/wp\/v2\/tags?post=6676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}